{"id":94,"date":"2016-01-16T21:58:00","date_gmt":"2016-01-16T20:58:00","guid":{"rendered":"http:\/\/new.sgs-sss.ch\/new\/?page_id=94"},"modified":"2025-01-07T11:40:26","modified_gmt":"2025-01-07T10:40:26","slug":"organe","status":"publish","type":"page","link":"https:\/\/sgs-sss.promideas.solutions\/de\/die-gesellschaft\/organe\/","title":{"rendered":"Organe"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4ywyu-0f360425ba4d966156018d923480aed8\">\n.avia-section.av-4ywyu-0f360425ba4d966156018d923480aed8{\nbackground-color:#ffffff;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-4ywyu-0f360425ba4d966156018d923480aed8 main_color avia-section-default avia-no-shadow  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-94'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4hsri-097557d83b36cd8a081d5124c1b3134e\">\n#top .av-special-heading.av-4hsri-097557d83b36cd8a081d5124c1b3134e{\npadding-bottom:25px;\n}\nbody .av-special-heading.av-4hsri-097557d83b36cd8a081d5124c1b3134e .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-4hsri-097557d83b36cd8a081d5124c1b3134e .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-4hsri-097557d83b36cd8a081d5124c1b3134e av-special-heading-h2  avia-builder-el-1  el_before_av_one_full  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >ORGANE<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-45hsa-26f995a582f9eea3379757114fe4494f\">\n.flex_column.av-45hsa-26f995a582f9eea3379757114fe4494f{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\n}\n<\/style>\n<div  class='flex_column av-45hsa-26f995a582f9eea3379757114fe4494f av_one_full  avia-builder-el-2  el_after_av_heading  avia-builder-el-last  first flex_column_div  '     ><section  class='av_textblock_section av-393i6-27460e2101410dcda5851f576c811ba6 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Die statutengem\u00e4ssen Organe der Gesellschaft sind: die Generalversammlung, der Vorstand, das B\u00fcro, der Beirat und die Kontrollstelle.<\/p>\n<h4><strong>Das B\u00fcro wird gebildet von:<\/strong><\/h4>\n<ul>\n<li>Claudine Burton-Jeangros (Pr\u00e4sidentin), Universit\u00e4t Genf, Soziologisches Department<\/li>\n<li>J\u00f6rg R\u00f6ssel (Vizepr\u00e4sident), Universit\u00e4t Z\u00fcrich, Soziologisches Institut<\/li>\n<li><span lang=\"FR-CH\">Andreas Hadjar<\/span> (Kassenf\u00fchrer), <span lang=\"FR-CH\">Universit\u00e4t Fribourg, Departement Sozialarbeit und Sozialpolitik<\/span><\/li>\n<li>Sekretariat c\/o Seismo Verlag, Z\u00fcrich<\/li>\n<\/ul>\n<h4><strong>Der Vorstand setzt sich aus folgenden Personen zusammen:<\/strong><\/h4>\n<ul>\n<li>Patrik Aspers, Universit\u00e4t St. Gallen, Seminar f\u00fcr Soziologie<\/li>\n<li>Philip Balsiger, Universit\u00e4t Neuch\u00e2tel, Institut f\u00fcr Soziologie<\/li>\n<li>Claudine Burton-Jeangros (Pr\u00e4sidentin), Universit\u00e4t Genf, Soziologisches Department<\/li>\n<li>Achim Edelmann, Universit\u00e4t Bern, Soziologisches Institut<\/li>\n<li><span lang=\"FR-CH\">Andreas Hadjar, Universit\u00e4t Fribourg, Departement Sozialarbeit und Sozialpolitik<\/span><\/li>\n<li>Emilie Rosenstein, Fachhochschule f\u00fcr Soziale Arbeit und Gesundheit Lausanne<\/li>\n<li>J\u00f6rg R\u00f6ssel, Universit\u00e4t Z\u00fcrich, Soziologisches Institut<\/li>\n<li>Stephanie Steinmetz, Universit\u00e4t Lausanne, Fakult\u00e4t f\u00fcr Sozial- und Politikwissenschaften<\/li>\n<\/ul>\n<h4><strong>Revisoren sind:<\/strong><\/h4>\n<ul>\n<li>Ben Jann (<span lang=\"DE-CH\">Universit\u00e4t Bern<\/span>)<\/li>\n<li><!-- &#091;if gte mso 9&#093;><xml>\n<w:WordDocument>\n<w:View>Normal<\/w:View>\n<w:Zoom>0<\/w:Zoom>\n<w:TrackMoves\/>\n<w:TrackFormatting\/>\n<w:HyphenationZone>21<\/w:HyphenationZone>\n<w:PunctuationKerning\/>\n<w:ValidateAgainstSchemas\/>\n<w:SaveIfXMLInvalid>false<\/w:SaveIfXMLInvalid>\n<w:IgnoreMixedContent>false<\/w:IgnoreMixedContent>\n<w:AlwaysShowPlaceholderText>false<\/w:AlwaysShowPlaceholderText>\n<w:DoNotPromoteQF\/>\n<w:LidThemeOther>DE-CH<\/w:LidThemeOther>\n<w:LidThemeAsian>X-NONE<\/w:LidThemeAsian>\n<w:LidThemeComplexScript>X-NONE<\/w:LidThemeComplexScript>\n<w:Compatibility>\n<w:BreakWrappedTables\/>\n<w:SnapToGridInCell\/>\n<w:WrapTextWithPunct\/>\n<w:UseAsianBreakRules\/>\n<w:DontGrowAutofit\/>\n<w:SplitPgBreakAndParaMark\/>\n<w:EnableOpenTypeKerning\/>\n<w:DontFlipMirrorIndents\/>\n<w:OverrideTableStyleHps\/>\n<\/w:Compatibility>\n<w:BrowserLevel>MicrosoftInternetExplorer4<\/w:BrowserLevel>\n<m:mathPr>\n<m:mathFont m:val=\"Cambria Math\"\/>\n<m:brkBin m:val=\"before\"\/>\n<m:brkBinSub m:val=\"--\"\/>\n<m:smallFrac m:val=\"off\"\/>\n<m:dispDef\/>\n<m:lMargin m:val=\"0\"\/>\n<m:rMargin m:val=\"0\"\/>\n<m:defJc m:val=\"centerGroup\"\/>\n<m:wrapIndent m:val=\"1440\"\/>\n<m:intLim m:val=\"subSup\"\/>\n<m:naryLim m:val=\"undOvr\"\/>\n<\/m:mathPr><\/w:WordDocument>\n<\/xml><!&#091;endif&#093;--><!-- &#091;if gte mso 9&#093;><xml>\n<w:LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"false\" DefSemiHidden=\"false\" DefQFormat=\"false\" DefPriority=\"99\" LatentStyleCount=\"375\">\n<w:LsdException Locked=\"false\" Priority=\"0\" QFormat=\"true\" Name=\"Normal\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 7\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 8\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"heading 9\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 7\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 8\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index 9\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 7\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 8\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toc 9\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal Indent\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footnote text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"header\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footer\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"index heading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"35\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"caption\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"table of figures\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"envelope address\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"envelope return\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"footnote reference\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation reference\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"line number\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"page number\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"endnote reference\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"endnote text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"table of authorities\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"macro\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"toa heading\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Bullet 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Number 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"10\" QFormat=\"true\" Name=\"Title\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Closing\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Signature\"\/>\n<w:LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Default Paragraph Font\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"List Continue 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Message Header\"\/>\n<w:LsdException Locked=\"false\" Priority=\"11\" QFormat=\"true\" Name=\"Subtitle\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Salutation\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Date\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text First Indent\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text First Indent 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Note Heading\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Body Text Indent 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Block Text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Hyperlink\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"FollowedHyperlink\"\/>\n<w:LsdException Locked=\"false\" Priority=\"22\" QFormat=\"true\" Name=\"Strong\"\/>\n<w:LsdException Locked=\"false\" Priority=\"20\" QFormat=\"true\" Name=\"Emphasis\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Document Map\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Plain Text\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"E-mail Signature\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Top of Form\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Bottom of Form\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal (Web)\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Acronym\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Address\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Cite\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Code\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Definition\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Keyboard\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Preformatted\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Sample\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Typewriter\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"HTML Variable\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Normal Table\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"annotation subject\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"No List\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Outline List 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Simple 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Classic 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Colorful 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Columns 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 7\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Grid 8\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 4\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 5\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 7\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table List 8\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table 3D effects 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Contemporary\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Elegant\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Professional\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Subtle 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Subtle 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 2\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Web 3\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Balloon Text\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"Table Grid\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Table Theme\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" Name=\"Placeholder Text\"\/>\n<w:LsdException Locked=\"false\" Priority=\"1\" QFormat=\"true\" Name=\"No Spacing\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" Name=\"Revision\"\/>\n<w:LsdException Locked=\"false\" Priority=\"34\" QFormat=\"true\" Name=\"List Paragraph\"\/>\n<w:LsdException Locked=\"false\" Priority=\"29\" QFormat=\"true\" Name=\"Quote\"\/>\n<w:LsdException Locked=\"false\" Priority=\"30\" QFormat=\"true\" Name=\"Intense Quote\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" Name=\"Light Shading Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" Name=\"Light List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" Name=\"Light Grid Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" Name=\"Medium Shading 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" Name=\"Medium Shading 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" Name=\"Medium List 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" Name=\"Medium List 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" Name=\"Medium Grid 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" Name=\"Medium Grid 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" Name=\"Medium Grid 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" Name=\"Dark List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" Name=\"Colorful Shading Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" Name=\"Colorful List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" Name=\"Colorful Grid Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"19\" QFormat=\"true\" Name=\"Subtle Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"21\" QFormat=\"true\" Name=\"Intense Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"31\" QFormat=\"true\" Name=\"Subtle Reference\"\/>\n<w:LsdException Locked=\"false\" Priority=\"32\" QFormat=\"true\" Name=\"Intense Reference\"\/>\n<w:LsdException Locked=\"false\" Priority=\"33\" QFormat=\"true\" Name=\"Book Title\"\/>\n<w:LsdException Locked=\"false\" Priority=\"37\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Bibliography\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" QFormat=\"true\" Name=\"TOC Heading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"41\" Name=\"Plain Table 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"42\" Name=\"Plain Table 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"43\" Name=\"Plain Table 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"44\" Name=\"Plain Table 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"45\" Name=\"Plain Table 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"40\" Name=\"Grid Table Light\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"Grid Table 1 Light Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"Grid Table 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"Grid Table 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"Grid Table 4 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"Grid Table 5 Dark Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"Grid Table 6 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"Grid Table 7 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"46\" Name=\"List Table 1 Light Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"47\" Name=\"List Table 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"48\" Name=\"List Table 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"49\" Name=\"List Table 4 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"50\" Name=\"List Table 5 Dark Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"51\" Name=\"List Table 6 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"52\" Name=\"List Table 7 Colorful Accent 6\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Mention\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Smart Hyperlink\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Hashtag\"\/>\n<w:LsdException Locked=\"false\" SemiHidden=\"true\" UnhideWhenUsed=\"true\" Name=\"Unresolved Mention\"\/>\n<\/w:LatentStyles>\n<\/xml><!&#091;endif&#093;--><!-- &#091;if gte mso 10&#093;>\n\n\n\n\n\n\n\n<style>\n \/* Style Definitions *\/<br \/> table.MsoNormalTable<br \/>\t{mso-style-name:\"Normale Tabelle\";<br \/>\tmso-tstyle-rowband-size:0;<br \/>\tmso-tstyle-colband-size:0;<br \/>\tmso-style-noshow:yes;<br \/>\tmso-style-priority:99;<br \/>\tmso-style-parent:\"\";<br \/>\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;<br \/>\tmso-para-margin:0cm;<br \/>\tmso-para-margin-bottom:.0001pt;<br \/>\tmso-pagination:widow-orphan;<br \/>\tfont-size:10.0pt;<br \/>\tfont-family:\"Times New Roman\",serif;}<br \/><\/style>\n\n\n\n\n\n<!&#091;endif&#093;--><span lang=\"DE-CH\">Cornelia Hummel (Universit\u00e4t Genf)<\/span><\/li>\n<\/ul>\n<p>Die Generalversammlung wird mindestens j\u00e4hrlich abgehalten. Die Protokolle vergangener Generalversammlungen sind hier abgelegt: <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2025\/01\/GA_SSA_2023_Protocol.pdf\">AG2023<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/10\/SSA_GA_Protocol_2022.pdf\">AG2022<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/10\/SSA_GA_Protocol_2021.pdf\">AG2021<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2021\/11\/201120_Minutes_GA.pdf\">AG2020<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2021\/03\/190911_Minutes_GA.pdf\">AG2019<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2019\/07\/AG2018.pdf\">AG2018<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2017\/11\/PV-AG.2017fr..pdf\">AG2017<\/a>,\u00a0<a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2017\/01\/PV-AG.2016-def.pdf\">AG2016<\/a>,\u00a0<a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/AG-2015.pdf\">AG2015<\/a>,\u00a0<a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/AG2014.pdf..\/wp-content\/uploads\/2016\/03\/AG2014-D.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2014<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/PVAGSSS_2013_fr.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2013<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/PVAGSSS_2012.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2012<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/PVAGSSS_2011.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2011<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/PVAGSSS_2010.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2010<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/AGSSS2009-1.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2009<\/a>, <a href=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/03\/Proces_verbal_AG_SSS_20080626_Neuchatel.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">AG2008<\/a>. Die Forschungskomitees bilden den aktiven wissenschaftlichen Kern der SGS. Ihr Ziel ist es die Forschung in Spezialgebieten der Disziplin voranzutreiben, den wissenschaftlichen Austausch zwischen Interessierten innerhalb von speziellen Soziologien zu erm\u00f6glichen und interessierte Adressatinnen und Adressaten auch ausserhalb zu erreichen. Eine Liste der Forschungskomitees mit weiteren Angaben finden und Hinweisen auf Veranstaltungen und Aktivit\u00e4ten findet sich hier.<\/p>\n<\/div><\/section><\/div><\/div><\/div><\/main><!-- close content main element --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2gfsi-d0c862d0a900231db880418f853e3b75\">\n.avia-section.av-2gfsi-d0c862d0a900231db880418f853e3b75{\nbackground-color:#eeeeee;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-2gfsi-d0c862d0a900231db880418f853e3b75 main_color avia-section-default avia-no-shadow  avia-builder-el-4  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-94'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-21ez2-4378cac2cd03b706bc5af453e19433ab\">\n#top .av-special-heading.av-21ez2-4378cac2cd03b706bc5af453e19433ab{\npadding-bottom:25px;\n}\nbody .av-special-heading.av-21ez2-4378cac2cd03b706bc5af453e19433ab .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-21ez2-4378cac2cd03b706bc5af453e19433ab .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-21ez2-4378cac2cd03b706bc5af453e19433ab av-special-heading-h2  avia-builder-el-5  el_before_av_one_full  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >AKTUELLES<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div class='flex_column_table av-1hgj6-d48756ee67413d2607a540ef42316277 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1hgj6-d48756ee67413d2607a540ef42316277\">\n.flex_column.av-1hgj6-d48756ee67413d2607a540ef42316277{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\n}\n<\/style>\n<div  class='flex_column av-1hgj6-d48756ee67413d2607a540ef42316277 av_one_full  avia-builder-el-6  el_after_av_heading  avia-builder-el-last  first no_margin flex_column_table_cell av-equal-height-column av-align-top  '     ><div  data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:&quot;5&quot;,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;show_slide_delay&quot;:90}\" class='avia-content-slider avia-content-slider-active avia-content-slider1 avia-content-slider-odd  avia-builder-el-7  avia-builder-el-no-sibling  av-slideshow-ui av-control-default   av-no-slider-navigation av-slideshow-autoplay av-loop-endless av-loop-manual-endless '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Blog\" ><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-21027 slide-entry-overview slide-loop-1 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-instruments\/' data-rel='slide-1' class='slide-image' title='Call for instruments'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"147\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-15-um-09.36.19.png\" class=\"wp-image-21024 avia-img-lazy-loading-not-21024 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for instruments\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-instruments\/' title='Call for instruments'>Call for instruments<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-15-um-09.36.19.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>458<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1544<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-10-15 09:41:47<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-10-15 09:41:47<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for instruments<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-21008 slide-entry-overview slide-loop-2 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-9\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"313\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-07-um-16.36.39.png\" class=\"wp-image-20998 avia-img-lazy-loading-not-20998 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-9\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-07-um-16.36.39.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>928<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1466<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-10-07 17:08:44<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-10-07 17:16:38<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20940 slide-entry-overview slide-loop-3 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstracts-4\/' data-rel='slide-1' class='slide-image' title='Call for Abstracts'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"154\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/08\/Bildschirmfoto-2024-08-19-um-09.39.03.png\" class=\"wp-image-20931 avia-img-lazy-loading-not-20931 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstracts\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstracts-4\/' title='Call for Abstracts'>Call for Abstracts<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/08\/Bildschirmfoto-2024-08-19-um-09.39.03.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>480<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1540<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-08-19 09:49:24<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-08-19 09:58:08<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstracts<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20766 slide-entry-overview slide-loop-4 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-contributions-for-the-ssa-bulletin-165\/' data-rel='slide-1' class='slide-image' title='Call for Contributions: SSA Bulletin 165'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"204\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-13-um-09.51.26-1.png\" class=\"wp-image-20763 avia-img-lazy-loading-not-20763 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Contributions: SSA Bulletin 165\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-contributions-for-the-ssa-bulletin-165\/' title='Call for Contributions: SSA Bulletin 165'>Call for Contributions: SSA Bulletin 165<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-13-um-09.51.26-1.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>484<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1172<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-05-13 16:48:57<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-13 18:51:53<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Contributions: SSA Bulletin 165<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20748 slide-entry-overview slide-loop-5 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/11e-festival-suisse-des-methodes-qualitatives\/' data-rel='slide-1' class='slide-image' title='11e Festival suisse des m\u00e9thodes qualitatives'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.45.09-495x400.png\" class=\"wp-image-20733 avia-img-lazy-loading-not-20733 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.45.09-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.45.09-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: 11e Festival suisse des m\u00e9thodes qualitatives\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/11e-festival-suisse-des-methodes-qualitatives\/' title='11e Festival suisse des m\u00e9thodes qualitatives'>11e Festival suisse des m\u00e9thodes qualitatives<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.45.09-e1715171771329.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>549<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-05-08 14:35:09<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-08 14:36:26<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>11e Festival suisse des m\u00e9thodes qualitatives<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20736 slide-entry-overview slide-loop-6 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-8\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-495x400.png\" class=\"wp-image-20724 avia-img-lazy-loading-not-20724 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-8\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-e1715165664974.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>420<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-05-08 12:54:41<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-08 12:54:41<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20457 slide-entry-overview slide-loop-7 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/10-schweizer-methodenfestival-zu-qualitativen-forschungsmethoden\/' data-rel='slide-1' class='slide-image' title='10. Schweizer Methoden\u00adfestival zu qualitativen Forschungs\u00admethoden \u2013 Verl\u00e4ngerung der Anmeldefrist'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"168\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-13-um-11.25.46-e1707821180992.png\" class=\"wp-image-20454 avia-img-lazy-loading-not-20454 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: 10. Schweizer Methoden\u00adfestival zu qualitativen Forschungs\u00admethoden \u2013 Verl\u00e4ngerung der Anmeldefrist\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/10-schweizer-methodenfestival-zu-qualitativen-forschungsmethoden\/' title='10. Schweizer Methoden\u00adfestival zu qualitativen Forschungs\u00admethoden \u2013 Verl\u00e4ngerung der Anmeldefrist'>10. Schweizer Methoden\u00adfestival zu qualitativen Forschungs\u00admethoden \u2013 Verl\u00e4ngerung der Anmeldefrist<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-05-03T12:49:32+02:00\" >03\/05\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-13-um-11.25.46-e1707821180992.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>170<\/span>\n\t\t\t\t\t\t<span itemprop='width'>500<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-05-03 12:49:32<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-03 12:48:56<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>10. Schweizer Methoden\u00adfestival zu qualitativen Forschungs\u00admethoden \u2013 Verl\u00e4ngerung der Anmeldefrist<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20695 slide-entry-overview slide-loop-8 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstracts-2\/' data-rel='slide-1' class='slide-image' title='Call for Abstracts'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"244\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-17.57.22.png\" class=\"wp-image-20689 avia-img-lazy-loading-not-20689 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstracts\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstracts-2\/' title='Call for Abstracts'>Call for Abstracts<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-05-03T12:49:32+02:00\" >03\/05\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-17.57.22.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>794<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1610<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-05-02 18:07:48<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-02 18:07:48<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstracts<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20670 slide-entry-overview slide-loop-9 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-7\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"224\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-15.23.36.png\" class=\"wp-image-20671 avia-img-lazy-loading-not-20671 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-7\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-05-03T12:49:32+02:00\" >03\/05\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-15.23.36.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>660<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1456<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-05-02 15:36:44<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-02 15:38:51<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20627 slide-entry-overview slide-loop-10 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstract-submissions\/' data-rel='slide-1' class='slide-image' title='Call for Abstract Submissions'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"212\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/03\/Bildschirmfoto-2024-03-25-um-16.11.43-e1711383706221.png\" class=\"wp-image-20621 avia-img-lazy-loading-not-20621 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstract Submissions\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstract-submissions\/' title='Call for Abstract Submissions'>Call for Abstract Submissions<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-05-03T12:49:32+02:00\" >03\/05\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/03\/Bildschirmfoto-2024-03-25-um-16.11.43-e1711383706221.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>218<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-03-25 17:27:06<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-03-25 17:27:06<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstract Submissions<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20501 slide-entry-overview slide-loop-11 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-6\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"226\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-21-um-14.51.30.png\" class=\"wp-image-20492 avia-img-lazy-loading-not-20492 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-6\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-05-03T12:49:32+02:00\" >03\/05\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-21-um-14.51.30.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>658<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1444<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-02-21 15:08:22<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-02-21 15:30:06<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20426 slide-entry-overview slide-loop-12 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstracts\/' data-rel='slide-1' class='slide-image' title='Call for Abstracts'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"161\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/01\/Bildschirmfoto-2024-01-31-um-16.19.51-e1706715089131.png\" class=\"wp-image-20420 avia-img-lazy-loading-not-20420 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstracts\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-abstracts\/' title='Call for Abstracts'>Call for Abstracts<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-01-31T16:30:04+01:00\" >31\/01\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/01\/Bildschirmfoto-2024-01-31-um-16.19.51-e1706715089131.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>163<\/span>\n\t\t\t\t\t\t<span itemprop='width'>500<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-01-31 16:30:04<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-01-31 16:34:00<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstracts<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20348 slide-entry-overview slide-loop-13 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-5\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"278\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-27-um-17.24.34-e1704277965384.png\" class=\"wp-image-20320 avia-img-lazy-loading-not-20320 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-5\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-01-31T16:30:04+01:00\" >31\/01\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-27-um-17.24.34-e1704277965384.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>286<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2024-01-03 11:24:50<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-01-03 11:55:50<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20239 slide-entry-overview slide-loop-14 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-4\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"280\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-14-um-10.25.30-e1702549692652-495x280.png\" class=\"wp-image-20222 avia-img-lazy-loading-not-20222 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-4\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-01-31T16:30:04+01:00\" >31\/01\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-14-um-10.25.30-e1702549692652.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>280<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-12-14 11:28:59<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-14 11:28:59<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20206 slide-entry-overview slide-loop-15 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-3\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"181\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-12-um-17.02.04-e1702398165140-495x181.png\" class=\"wp-image-20194 avia-img-lazy-loading-not-20194 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-3\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-01-31T16:30:04+01:00\" >31\/01\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-12-um-17.02.04-e1702398165140.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>181<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-12-12 17:23:06<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-12 17:23:25<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20140 slide-entry-overview slide-loop-16 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-2\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"160\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-07-um-09.55.32-1-e1701940141658-495x160.png\" class=\"wp-image-20145 avia-img-lazy-loading-not-20145 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-2\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2024-01-31T16:30:04+01:00\" >31\/01\/2024<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-07-um-09.55.32-1-e1701940141658.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>160<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-12-07 10:04:53<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-07 10:10:19<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-19762 slide-entry-overview slide-loop-17 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/conference\/' data-rel='slide-1' class='slide-image' title='Conference'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/10\/Bildschirmfoto-2023-10-20-um-13.58.36-495x400.png\" class=\"wp-image-19753 avia-img-lazy-loading-not-19753 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/10\/Bildschirmfoto-2023-10-20-um-13.58.36-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/10\/Bildschirmfoto-2023-10-20-um-13.58.36-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Conference\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/conference\/' title='Conference'>Conference<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-10-20T14:14:47+02:00\" >20\/10\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/10\/Bildschirmfoto-2023-10-20-um-13.58.36.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1210<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1354<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-10-20 14:14:47<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-10-20 14:14:47<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Conference<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-19079 slide-entry-overview slide-loop-18 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/19079\/' data-rel='slide-1' class='slide-image' title='Conference'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33-495x400.png\" class=\"wp-image-19075 avia-img-lazy-loading-not-19075 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Conference\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/19079\/' title='Conference'>Conference<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:53:47+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1018<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1272<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-07-12 10:53:47<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-07-12 10:54:51<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Conference<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-18704 slide-entry-overview slide-loop-19 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-44\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.23.39-495x400.png\" class=\"wp-image-18700 avia-img-lazy-loading-not-18700 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.23.39-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.23.39-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-44\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:53:47+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.23.39.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>714<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1940<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-05-30 15:29:32<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-10-04 14:00:56<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-17847 slide-entry-overview slide-loop-20 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-question-contributions-2\/' data-rel='slide-1' class='slide-image' title='Call for Question Contributions'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"134\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/03\/Bildschirmfoto-2022-03-01-um-14.20.49-495x134.png\" class=\"wp-image-16168 avia-img-lazy-loading-not-16168 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Question Contributions\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-question-contributions-2\/' title='Call for Question Contributions'>Call for Question Contributions<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:53:47+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/03\/Bildschirmfoto-2022-03-01-um-14.20.49.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>134<\/span>\n\t\t\t\t\t\t<span itemprop='width'>524<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2023-01-04 18:13:28<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-01-04 18:13:28<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Question Contributions<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-17650 slide-entry-overview slide-loop-21 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-41\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-12-01-um-10.20.53-495x400.png\" class=\"wp-image-17648 avia-img-lazy-loading-not-17648 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-12-01-um-10.20.53-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-12-01-um-10.20.53-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-41\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:53:47+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-12-01-um-10.20.53.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>708<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2106<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2022-12-01 10:42:02<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-12-01 10:42:02<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-17601 slide-entry-overview slide-loop-22 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-40\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-1-495x400.png\" class=\"wp-image-17630 avia-img-lazy-loading-not-17630 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-1-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-1-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/call-for-papers-40\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:53:47+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-1.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1562<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2568<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2022-11-28 15:45:48<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-11-28 16:05:36<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-17337 slide-entry-overview slide-loop-23 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/soziologischer-comic\/' data-rel='slide-1' class='slide-image' title='Soziologischer Comic'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21-495x400.png\" class=\"wp-image-17350 avia-img-lazy-loading-not-17350 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Soziologischer Comic\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/soziologischer-comic\/' title='Soziologischer Comic'>Soziologischer Comic<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2022-10-17T14:46:28+02:00\" >17\/10\/2022<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1476<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1430<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2022-10-17 14:46:28<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-10-17 14:51:46<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Soziologischer Comic<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-16641 slide-entry-overview slide-loop-24 slide-parity-odd  post-entry-last  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/snsf-support-for-ukrainian-scholars\/' data-rel='slide-1' class='slide-image' title='SNSF support for scientists from Ukraine'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-495x400.png\" class=\"wp-image-16643 avia-img-lazy-loading-not-16643 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-300x242.png 300w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-1030x832.png 1030w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-768x621.png 768w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-845x684.png 845w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43-705x570.png 705w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43.png 1458w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: SNSF support for scientists from Ukraine\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/de\/category\/allgemein\/\" rel=\"tag\">Allgemeine News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/de\/snsf-support-for-ukrainian-scholars\/' title='SNSF support for scientists from Ukraine'>SNSF support for scientists from Ukraine<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2022-05-17T08:44:45+02:00\" >17\/05\/2022<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1178<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1458<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-01-16T21:58:00+01:00\" >2022-05-17 08:44:45<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-05-17 09:14:08<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>SNSF support for scientists from Ukraine<\/span><\/span><\/span><\/article><\/div><\/div><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide ' aria-hidden='true' data-av_icon='\ue87c' data-av_iconfont='entypo-fontello'  tabindex='-1'>Zur\u00fcck<\/a><a href='#next' class='next-slide ' aria-hidden='true' data-av_icon='\ue87d' data-av_iconfont='entypo-fontello'  tabindex='-1'>Weiter<\/a><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":21,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-94","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/pages\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":64,"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/pages\/94\/revisions"}],"predecessor-version":[{"id":21243,"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/pages\/94\/revisions\/21243"}],"up":[{"embeddable":true,"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/pages\/21"}],"wp:attachment":[{"href":"https:\/\/sgs-sss.promideas.solutions\/de\/wp-json\/wp\/v2\/media?parent=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}