{"id":651,"date":"2016-02-11T20:27:11","date_gmt":"2016-02-11T19:27:11","guid":{"rendered":"http:\/\/new.sgs-sss.ch\/new\/fr\/soziologische-theorie-und-theoriegeschichte\/"},"modified":"2016-04-19T16:04:42","modified_gmt":"2016-04-19T14:04:42","slug":"theorie-sociologique-et-histoire-de-la-theorie","status":"publish","type":"page","link":"https:\/\/sgs-sss.promideas.solutions\/fr\/comites-de-recherche\/theorie-sociologique-et-histoire-de-la-theorie\/","title":{"rendered":"Th\u00e9orie sociologique et histoire de la th\u00e9orie"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-fb37fa88fbca848c7e29aff3fecdfcf1\">\n.avia-section.av-av_section-fb37fa88fbca848c7e29aff3fecdfcf1{\nbackground-color:#ffffff;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-av_section-fb37fa88fbca848c7e29aff3fecdfcf1 main_color avia-section-default avia-no-shadow  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-651'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-4cc799d6fa2dfc6de91420bda5192f7a\">\n#top .av-special-heading.av-av_heading-4cc799d6fa2dfc6de91420bda5192f7a{\npadding-bottom:25px;\n}\nbody .av-special-heading.av-av_heading-4cc799d6fa2dfc6de91420bda5192f7a .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-4cc799d6fa2dfc6de91420bda5192f7a .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-4cc799d6fa2dfc6de91420bda5192f7a av-special-heading-h2  avia-builder-el-1  el_before_av_one_full  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >TH\u00c9ORIE SOCIOLOGIQUE ET HISTOIRE DE LA TH\u00c9ORIE<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div class='flex_column_table av-av_one_full-637497d8078788bf7892f1875f6d3165 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-637497d8078788bf7892f1875f6d3165\">\n.flex_column.av-av_one_full-637497d8078788bf7892f1875f6d3165{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-637497d8078788bf7892f1875f6d3165 av_one_full  avia-builder-el-2  el_after_av_heading  avia-builder-el-last  first no_margin flex_column_table_cell av-equal-height-column av-align-top  '     ><section  class='av_textblock_section av-av_textblock-0366cc7376be6c9e82a3e9cc8987b64f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><blockquote>\n<h3><strong>Portrait <\/strong><\/h3>\n<p>Le comit\u00e9 de recherche sur la th\u00e9orie sociologique et l&rsquo;histoire de la th\u00e9orie a \u00e9t\u00e9 fond\u00e9 en 2001. Il se r\u00e9unit chaque ann\u00e9e pour d\u00e9finir les th\u00e8mes d&rsquo;\u00e9tude, que les membres souhaitent approfondir.<\/p>\n<p>Derni\u00e8rement, il a analys\u00e9 le fonctionalisme et la communaut\u00e9.<\/p>\n<p><a href=\"https:\/\/sgs-sss.promideas.solutions\/forschungskomitees\/soziologische-theorie-und-theoriegeschichte\" target=\"_blank\" rel=\"noopener\">Plus de d\u00e9tails en allemand<\/a><\/p>\n<\/blockquote>\n<\/div><\/section><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/div><\/div><\/main><!-- close content main element --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-f1bb2109ee22ed978ff4c4c9a3816abd\">\n.avia-section.av-av_section-f1bb2109ee22ed978ff4c4c9a3816abd{\nbackground-color:#eeeeee;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-av_section-f1bb2109ee22ed978ff4c4c9a3816abd main_color avia-section-default avia-no-shadow  avia-builder-el-4  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-651'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-5440abcb82753a726aa888ca2b954fe6\">\n#top .av-special-heading.av-av_heading-5440abcb82753a726aa888ca2b954fe6{\npadding-bottom:25px;\n}\nbody .av-special-heading.av-av_heading-5440abcb82753a726aa888ca2b954fe6 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-5440abcb82753a726aa888ca2b954fe6 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-5440abcb82753a726aa888ca2b954fe6 av-special-heading-h2  avia-builder-el-5  el_before_av_one_full  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >NEWS<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div class='flex_column_table av-av_one_full-637497d8078788bf7892f1875f6d3165 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-637497d8078788bf7892f1875f6d3165\">\n.flex_column.av-av_one_full-637497d8078788bf7892f1875f6d3165{\nborder-radius:0px 0px 0px 0px;\npadding:20px 20px 20px 20px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-637497d8078788bf7892f1875f6d3165 av_one_full  avia-builder-el-6  el_after_av_heading  avia-builder-el-last  first no_margin flex_column_table_cell av-equal-height-column av-align-top  '     ><div  data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:&quot;5&quot;,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;show_slide_delay&quot;:90}\" class='avia-content-slider avia-content-slider-active avia-content-slider1 avia-content-slider-odd  avia-builder-el-7  avia-builder-el-no-sibling  av-slideshow-ui av-control-default   av-no-slider-navigation av-slideshow-autoplay av-loop-endless av-loop-manual-endless '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Blog\" ><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-21033 slide-entry-overview slide-loop-1 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-instruments\/' data-rel='slide-1' class='slide-image' title='Call for instruments'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"147\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-15-um-09.36.19.png\" class=\"wp-image-21026 avia-img-lazy-loading-not-21026 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for instruments\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-instruments\/' title='Call for instruments'>Call for instruments<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-15-um-09.36.19.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>458<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1544<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-10-15 09:47:55<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-10-15 09:47:55<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for instruments<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20999 slide-entry-overview slide-loop-2 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-9\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"313\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-07-um-16.36.39.png\" class=\"wp-image-20996 avia-img-lazy-loading-not-20996 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-9\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/10\/Bildschirmfoto-2024-10-07-um-16.36.39.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>928<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1466<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-10-07 17:00:06<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-10-07 17:12:46<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20928 slide-entry-overview slide-loop-3 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstracts-4\/' data-rel='slide-1' class='slide-image' title='Call for Abstracts'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"154\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/08\/Bildschirmfoto-2024-08-19-um-09.39.03.png\" class=\"wp-image-20929 avia-img-lazy-loading-not-20929 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstracts\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstracts-4\/' title='Call for Abstracts'>Call for Abstracts<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/08\/Bildschirmfoto-2024-08-19-um-09.39.03.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>480<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1540<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-08-19 09:49:24<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-08-19 09:50:54<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstracts<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20772 slide-entry-overview slide-loop-4 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-contributions-ssa-bulletin-165\/' data-rel='slide-1' class='slide-image' title='Call for Contributions: SSA Bulletin 165'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"204\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-13-um-09.51.26-1.png\" class=\"wp-image-20765 avia-img-lazy-loading-not-20765 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Contributions: SSA Bulletin 165\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-contributions-ssa-bulletin-165\/' title='Call for Contributions: SSA Bulletin 165'>Call for Contributions: SSA Bulletin 165<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-13-um-09.51.26-1.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>484<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1172<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-05-13 16:56:27<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-13 18:51:13<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Contributions: SSA Bulletin 165<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20745 slide-entry-overview slide-loop-5 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/11e-festival-suisse-des-methodes-qualitatives\/' data-rel='slide-1' class='slide-image' title='11e Festival suisse des m\u00e9thodes qualitatives'><img decoding=\"async\" fetchpriority=\"high\" width=\"371\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.45.09.png\" class=\"wp-image-20735 avia-img-lazy-loading-not-20735 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: 11e Festival suisse des m\u00e9thodes qualitatives\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/11e-festival-suisse-des-methodes-qualitatives\/' title='11e Festival suisse des m\u00e9thodes qualitatives'>11e Festival suisse des m\u00e9thodes qualitatives<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.45.09.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1254<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1164<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-05-08 14:30:45<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-08 14:52:39<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>11e Festival suisse des m\u00e9thodes qualitatives<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20742 slide-entry-overview slide-loop-6 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-8\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-495x400.png\" class=\"wp-image-20726 avia-img-lazy-loading-not-20726 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-8\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-08-um-12.07.07-e1715165664974.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1126<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1366<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-05-08 13:00:43<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-08 13:00:43<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20467 slide-entry-overview slide-loop-7 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/10-schweizer-methodenfestival\/' data-rel='slide-1' class='slide-image' title='10. Schweizer Methodenfestival  \u2013 Anmeldefrist verl\u00e4ngert'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"168\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-13-um-11.25.46-e1707822675536.png\" class=\"wp-image-20456 avia-img-lazy-loading-not-20456 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: 10. Schweizer Methodenfestival  \u2013 Anmeldefrist verl\u00e4ngert\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/10-schweizer-methodenfestival\/' title='10. Schweizer Methodenfestival  \u2013 Anmeldefrist verl\u00e4ngert'>10. Schweizer Methodenfestival  \u2013 Anmeldefrist verl\u00e4ngert<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-13-um-11.25.46-e1707822675536.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>170<\/span>\n\t\t\t\t\t\t<span itemprop='width'>500<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-05-03 12:22:43<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-03 12:33:17<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>10. Schweizer Methodenfestival  \u2013 Anmeldefrist verl\u00e4ngert<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20702 slide-entry-overview slide-loop-8 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstracts-2\/' data-rel='slide-1' class='slide-image' title='Call for Abstracts'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"244\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-17.57.22.png\" class=\"wp-image-20691 avia-img-lazy-loading-not-20691 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstracts\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstracts-2\/' title='Call for Abstracts'>Call for Abstracts<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-17.57.22.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>794<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1610<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-05-02 18:18:35<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-02 18:18:35<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstracts<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20686 slide-entry-overview slide-loop-9 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-7\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"224\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-15.23.36.png\" class=\"wp-image-20673 avia-img-lazy-loading-not-20673 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-7\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/05\/Bildschirmfoto-2024-05-02-um-15.23.36.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>660<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1456<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-05-02 15:56:52<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-05-02 15:58:52<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20633 slide-entry-overview slide-loop-10 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstract-submissions\/' data-rel='slide-1' class='slide-image' title='Call for Abstract Submissions'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"212\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/03\/Bildschirmfoto-2024-03-25-um-16.11.43-e1711383706221.png\" class=\"wp-image-20623 avia-img-lazy-loading-not-20623 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Abstract Submissions\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstract-submissions\/' title='Call for Abstract Submissions'>Call for Abstract Submissions<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/03\/Bildschirmfoto-2024-03-25-um-16.11.43-e1711383706221.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>624<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1460<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-03-25 17:45:06<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-03-25 17:45:06<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Abstract Submissions<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20504 slide-entry-overview slide-loop-11 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-6\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"226\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-21-um-14.51.30-1.png\" class=\"wp-image-20497 avia-img-lazy-loading-not-20497 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-6\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/02\/Bildschirmfoto-2024-02-21-um-14.51.30-1.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>658<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1444<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-02-21 15:21:07<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-02-21 15:31:09<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20438 slide-entry-overview slide-loop-12 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstracts\/' data-rel='slide-1' class='slide-image' title='Call for abstracts'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"161\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/01\/Bildschirmfoto-2024-01-31-um-16.19.51-2-e1706716556546.png\" class=\"wp-image-20441 avia-img-lazy-loading-not-20441 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for abstracts\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-abstracts\/' title='Call for abstracts'>Call for abstracts<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2024\/01\/Bildschirmfoto-2024-01-31-um-16.19.51-2-e1706716556546.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>163<\/span>\n\t\t\t\t\t\t<span itemprop='width'>500<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2024-01-31 16:56:48<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2024-01-31 16:56:48<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for abstracts<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20317 slide-entry-overview slide-loop-13 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-5\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"278\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-27-um-17.24.34-e1703695592107.png\" class=\"wp-image-20318 avia-img-lazy-loading-not-20318 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-5\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-12-27T17:42:22+01:00\" >27\/12\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-27-um-17.24.34-e1703695592107.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>286<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-12-27 17:42:22<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-27 17:47:01<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20223 slide-entry-overview slide-loop-14 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-4\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"280\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-14-um-10.25.30-e1702546298519-495x280.png\" class=\"wp-image-20220 avia-img-lazy-loading-not-20220 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-4\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-12-27T17:42:22+01:00\" >27\/12\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-14-um-10.25.30-e1702546298519.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>280<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-12-14 11:10:39<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-14 11:23:58<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-20202 slide-entry-overview slide-loop-15 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-3\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"181\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-12-um-17.02.04-e1702397939237-495x181.png\" class=\"wp-image-20193 avia-img-lazy-loading-not-20193 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-3\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-12-27T17:42:22+01:00\" >27\/12\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-12-um-17.02.04-e1702397939237.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>181<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-12-12 17:19:14<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-12 17:19:14<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-20154 slide-entry-overview slide-loop-16 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-2\/' data-rel='slide-1' class='slide-image' title='Call for Papers'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"160\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-07-um-09.55.32-1-e1701940404330-495x160.png\" class=\"wp-image-20147 avia-img-lazy-loading-not-20147 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Papers\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-papers-2\/' title='Call for Papers'>Call for Papers<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-12-27T17:42:22+01:00\" >27\/12\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/12\/Bildschirmfoto-2023-12-07-um-09.55.32-1-e1701940404330.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>160<\/span>\n\t\t\t\t\t\t<span itemprop='width'>510<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-12-07 10:13:34<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-12-07 10:13:34<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Papers<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-19088 slide-entry-overview slide-loop-17 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/conference\/' data-rel='slide-1' class='slide-image' title='Conference'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33-495x400.png\" class=\"wp-image-19077 avia-img-lazy-loading-not-19077 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Conference\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/conference\/' title='Conference'>Conference<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:59:09+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/07\/Bildschirmfoto-2023-07-12-um-10.18.33.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1018<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1272<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-07-12 10:59:09<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-07-12 10:59:09<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Conference<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-18712 slide-entry-overview slide-loop-18 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/appel-a-participation\/' data-rel='slide-1' class='slide-image' title='Appel \u00e0 participation'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.30.49-495x400.png\" class=\"wp-image-18709 avia-img-lazy-loading-not-18709 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.30.49-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.30.49-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Appel \u00e0 participation\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/appel-a-participation\/' title='Appel \u00e0 participation'>Appel \u00e0 participation<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:59:09+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2023\/05\/Bildschirmfoto-2023-05-30-um-15.30.49.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>826<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2134<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-05-30 15:38:21<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-08-18 13:45:43<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Appel \u00e0 participation<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-17843 slide-entry-overview slide-loop-19 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-question-contributions-2\/' data-rel='slide-1' class='slide-image' title='Call for Question Contributions'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"134\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/03\/Bildschirmfoto-2022-03-01-um-14.20.49-495x134.png\" class=\"wp-image-16167 avia-img-lazy-loading-not-16167 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Call for Question Contributions\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/call-for-question-contributions-2\/' title='Call for Question Contributions'>Call for Question Contributions<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:59:09+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/03\/Bildschirmfoto-2022-03-01-um-14.20.49.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>134<\/span>\n\t\t\t\t\t\t<span itemprop='width'>524<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2023-01-04 18:11:46<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2023-01-04 18:11:46<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Call for Question Contributions<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-17617 slide-entry-overview slide-loop-20 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/appel-a-contribution-5\/' data-rel='slide-1' class='slide-image' title='Appel \u00e0 contribution'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"301\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20.png\" class=\"wp-image-17622 avia-img-lazy-loading-not-17622 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20.png 2568w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-300x182.png 300w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-1030x627.png 1030w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-768x467.png 768w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-1536x934.png 1536w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20-2048x1246.png 2048w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Appel \u00e0 contribution\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/appel-a-contribution-5\/' title='Appel \u00e0 contribution'>Appel \u00e0 contribution<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:59:09+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-28-um-15.58.20.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1562<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2568<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2022-11-28 15:54:53<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-11-28 15:59:55<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Appel \u00e0 contribution<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-17479 slide-entry-overview slide-loop-21 slide-parity-odd  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/appel-a-contribution-4\/' data-rel='slide-1' class='slide-image' title='Appel \u00e0 contribution'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-10-um-11.44.40-495x400.png\" class=\"wp-image-17475 avia-img-lazy-loading-not-17475 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-10-um-11.44.40-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-10-um-11.44.40-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Appel \u00e0 contribution\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/appel-a-contribution-4\/' title='Appel \u00e0 contribution'>Appel \u00e0 contribution<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-12T10:59:09+02:00\" >12\/07\/2023<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-11-10-um-11.44.40.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>950<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2068<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2022-11-10 11:52:14<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-11-10 11:53:52<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Appel \u00e0 contribution<\/span><\/span><\/span><\/article><\/div><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-17367 slide-entry-overview slide-loop-22 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/bande-dessinee-sociologique\/' data-rel='slide-1' class='slide-image' title='Bande dessin\u00e9e sociologique'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21-495x400.png\" class=\"wp-image-17352 avia-img-lazy-loading-not-17352 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21-495x400.png 495w, https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21-845x684.png 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Bande dessin\u00e9e sociologique\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/bande-dessinee-sociologique\/' title='Bande dessin\u00e9e sociologique'>Bande dessin\u00e9e sociologique<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2022-10-17T15:07:07+02:00\" >17\/10\/2022<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/10\/Bildschirmfoto-2022-10-17-um-14.38.21.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1476<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1430<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2022-10-17 15:07:07<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-10-17 15:07:07<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Bande dessin\u00e9e sociologique<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-16663 slide-entry-overview slide-loop-23 slide-parity-even  post-entry-last  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/snsf-support-for-scientists-from-ukraine\/' data-rel='slide-1' class='slide-image' title='SNSF support for scientists from Ukraine'><img decoding=\"async\" fetchpriority=\"high\" width=\"1\" height=\"1\" src=\"https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43.png\" class=\"wp-image-16645 avia-img-lazy-loading-not-16645 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: SNSF support for scientists from Ukraine\"><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/sgs-sss.promideas.solutions\/fr\/category\/news\/\" rel=\"tag\">News<\/a> <\/span><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/sgs-sss.promideas.solutions\/fr\/snsf-support-for-scientists-from-ukraine\/' title='SNSF support for scientists from Ukraine'>SNSF support for scientists from Ukraine<\/a><\/h3><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >\r\n\r\n<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2022-05-17T09:16:12+02:00\" >17\/05\/2022<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2022\/04\/Bildschirmfoto-2022-05-17-um-08.23.43.png<\/span>\n\t\t\t\t\t\t<span itemprop='height'>0<\/span>\n\t\t\t\t\t\t<span itemprop='width'>0<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>keller<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/sgs-sss.promideas.solutions\/wp-content\/uploads\/2016\/01\/logo.jpg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>keller<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2016-02-11T20:27:11+01:00\" >2022-05-17 09:16:12<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2022-05-17 09:50:31<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>SNSF support for scientists from Ukraine<\/span><\/span><\/span><\/article><\/div><\/div><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide ' aria-hidden='true' data-av_icon='\ue87c' data-av_iconfont='entypo-fontello'  tabindex='-1'>Pr\u00e9c\u00e9dent<\/a><a href='#next' class='next-slide ' aria-hidden='true' data-av_icon='\ue87d' data-av_iconfont='entypo-fontello'  tabindex='-1'>Suivant<\/a><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":655,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-651","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/pages\/651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/comments?post=651"}],"version-history":[{"count":4,"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/pages\/651\/revisions"}],"predecessor-version":[{"id":959,"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/pages\/651\/revisions\/959"}],"up":[{"embeddable":true,"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/pages\/655"}],"wp:attachment":[{"href":"https:\/\/sgs-sss.promideas.solutions\/fr\/wp-json\/wp\/v2\/media?parent=651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}